{"id":1223,"date":"2018-10-29T10:00:19","date_gmt":"2018-10-29T09:00:19","guid":{"rendered":"https:\/\/www.pedagogia.it\/stripes\/?p=1223"},"modified":"2018-10-29T10:00:19","modified_gmt":"2018-10-29T09:00:19","slug":"habitare-linfanzia-20-10-2018-liberthub-monza","status":"publish","type":"post","link":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/","title":{"rendered":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza"},"content":{"rendered":"<p>Anche a Monza \u00e8 ufficialmente partito <a href=\"https:\/\/www.pedagogia.it\/stripes\/hubin\/\">HUB-IN: Luoghi per crescere insieme.<\/a><br \/>\nIl progetto biennale selezionato da Fondazione Con I Bambini nell\u2019ambito del contrasto della povert\u00e0 educativa, vede nella giornata di sabato 22 ottobre il suo inizio con l\u2019evento: <strong>HABITARE L\u2019INFANZIA.<\/strong><br \/>\nL\u2019impegno dei partner, tra cui la Cooperativa Sociale Stripes Onlus (capofila), il Comune di Monza, il Consorzio Comunit\u00e0 Brianza, Coop. Empiria, Coop. Meta, Coop. Novomillennio, Desbri, Movimento Africa 70, nel realizzare questa giornata densa di laboratori, esperienze ed incontri \u00e8 stato enorme.<br \/>\nIl luogo di questo bell\u2019evento \u00e8 stato il centro civico Liberthub di viale Libert\u00e0 144, Monza.<br \/>\nLa partecipazione numerosa ed attiva delle famiglie e di tutti i soggetti coinvolti, la loro risposta entusiasta, positiva e propositiva, ci portano a credere che questo sia l\u2019inizio di un percorso intenso e coinvolgente, denso di scambi e novit\u00e0, volto a migliorarci come singoli e come comunit\u00e0.<br \/>\nLe esperienze proposte sono state molte:<br \/>\n<strong>\u201cUn t\u00e8 con la pedagogista\u201d<\/strong>, nato da alcune suggestioni fornite ai genitori sul \u201ccosa dire e come parlare\u201d ai propri figli a permesso di ampliare la riflessione tra pedagogista e genitori . La \u201cchiacchierata\u201d \u00e8 stata cosi interessante, da far richiedere ai partecipanti altri incontri con la pedagogista.<br \/>\n<strong>\u201cYoga bimbi e yoga mamma-bimbo\u201d<\/strong>, coccole, relax e relazione attraverso una rivisitazione giocosa e divertente di una delle discipline pi\u00f9 antiche . Il laboratorio sar\u00e0 attivato tutti i gioved\u00ec da novembre 2018 a gennaio 2019!<br \/>\n<strong>\u201cIncontro con Art\u00f9\u201d<\/strong>, l\u2019amico a quattro zampe capace di cercare stuzzichini, si \u00e8 dimostrato un\u2019infaticabile coccolone. Anche in questo caso, la partecipazione dei bambini \u00e8 stata euforica! Ci ha fatto molto riflettere su come spesso non sia necessario usare grandi termini per potersi comprendere ed interagire, anche se avere una coda ed un muso da orsacchiotto aiuta.<br \/>\n<strong>\u201cPennelli alternativi\u201d<\/strong>, laboratorio in cui i bambini hanno potuto sperimentare materiali naturali differenti per forma, consistenza, colore, odore\u2026per \u201clasciare il loro segno\u201d su un enorme foglio ma non solo\u2026<br \/>\n<strong>\u201cL\u2019omino della pioggia\u201d<\/strong>, laboratorio teatrale ispirato alla favola di Gianni Rodari. Dopo aver assistito alla rappresentazione, tutti i \u201cpiccoli attori\u201d si sono dati un gran daffare per aprire e chiudere i rubinetti delle nuvole, creando cascate di chicchi di riso, lenticchie e chi pi\u00f9 ne ha pi\u00f9 ne metta!<\/p>\n<p><strong>\u201cGiocare all\u2019aperto quando piove\u201d<\/strong>, la mostra fotografica che \u201cfluttua tra le nuvole\u201d.<br \/>\nAllestita in modo originale e suggestivo, lungo un corridoio azzurro con delle nuvolette dalle quali cadevano gocce, fatte per\u00f2 di foto e di disegni dei bambini che hanno sperimentato l\u2019esperienza di outdoor education di giocare con la pioggia.<br \/>\n<strong>\u201cBaby baratto d\u2019autunno\u201d<\/strong> e <strong>\u201cMi Fido di Noi\u201d<\/strong> spazi sia fisici che virtuali per cambiare<br \/>\nindumenti, giochi, libri e materiali che non ci servono pi\u00f9 ma\u2026anche per scambiarsi idee e consigli tra genitori, per condividere hobbies e buone pratiche. Non un semplice baratto quindi, ma la creazione di una rete di scambio a 360 gradi.<br \/>\nLa giornata si \u00e8 conclusa con un aperitivo, i saluti dell\u2019Assessore Merlini dell\u2019Amministrazione di Monza e l\u2019immancabile <strong>\u201cfebbre del sabato sera spazio dance\u201d;<\/strong> con tanta stanchezza ma col sorriso sulle labbra; con la consapevolezza di aver seminato bene e l\u2019aspettativa di vedere da quei semi crescere alberi dalle forti radici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche a Monza \u00e8 ufficialmente partito HUB-IN: Luoghi per crescere insieme. Il progetto biennale selezionato da Fondazione Con I Bambini [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":1224,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-1223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bloghubin"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS\" \/>\n<meta property=\"og:description\" content=\"Anche a Monza \u00e8 ufficialmente partito HUB-IN: Luoghi per crescere insieme. Il progetto biennale selezionato da Fondazione Con I Bambini [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/\" \/>\n<meta property=\"og:site_name\" content=\"Stripes Cooperativa Sociale ONLUS\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-29T09:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1272\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"saradibruno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"saradibruno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/\"},\"author\":{\"name\":\"saradibruno\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/586afcb957e1d494e8fc69f4c0907fb7\"},\"headline\":\"HABITARE L\u2019INFANZIA 20\\\/10\\\/2018 Liberthub-Monza\",\"datePublished\":\"2018-10-29T09:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/\"},\"wordCount\":531,\"image\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/2.jpg\",\"articleSection\":[\"Blog Hub-In\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/\",\"name\":\"HABITARE L\u2019INFANZIA 20\\\/10\\\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/2.jpg\",\"datePublished\":\"2018-10-29T09:00:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/586afcb957e1d494e8fc69f4c0907fb7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/10\\\/2.jpg\",\"width\":1272,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/habitare-linfanzia-20-10-2018-liberthub-monza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HABITARE L\u2019INFANZIA 20\\\/10\\\/2018 Liberthub-Monza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#website\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/\",\"name\":\"Stripes Cooperativa Sociale ONLUS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/586afcb957e1d494e8fc69f4c0907fb7\",\"name\":\"saradibruno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g3e7d60ade7c55b80f984adf695fb79c8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g\",\"caption\":\"saradibruno\"},\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/author\\\/saradibruno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/","og_locale":"it_IT","og_type":"article","og_title":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS","og_description":"Anche a Monza \u00e8 ufficialmente partito HUB-IN: Luoghi per crescere insieme. Il progetto biennale selezionato da Fondazione Con I Bambini [&hellip;]","og_url":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/","og_site_name":"Stripes Cooperativa Sociale ONLUS","article_published_time":"2018-10-29T09:00:19+00:00","og_image":[{"width":1272,"height":500,"url":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg","type":"image\/jpeg"}],"author":"saradibruno","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"saradibruno","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#article","isPartOf":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/"},"author":{"name":"saradibruno","@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/586afcb957e1d494e8fc69f4c0907fb7"},"headline":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza","datePublished":"2018-10-29T09:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/"},"wordCount":531,"image":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg","articleSection":["Blog Hub-In"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/","url":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/","name":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza - Stripes Cooperativa Sociale ONLUS","isPartOf":{"@id":"https:\/\/www.pedagogia.it\/stripes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#primaryimage"},"image":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg","datePublished":"2018-10-29T09:00:19+00:00","author":{"@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/586afcb957e1d494e8fc69f4c0907fb7"},"breadcrumb":{"@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#primaryimage","url":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg","contentUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/10\/2.jpg","width":1272,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.pedagogia.it\/stripes\/habitare-linfanzia-20-10-2018-liberthub-monza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pedagogia.it\/stripes\/"},{"@type":"ListItem","position":2,"name":"HABITARE L\u2019INFANZIA 20\/10\/2018 Liberthub-Monza"}]},{"@type":"WebSite","@id":"https:\/\/www.pedagogia.it\/stripes\/#website","url":"https:\/\/www.pedagogia.it\/stripes\/","name":"Stripes Cooperativa Sociale ONLUS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pedagogia.it\/stripes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/586afcb957e1d494e8fc69f4c0907fb7","name":"saradibruno","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g3e7d60ade7c55b80f984adf695fb79c8","url":"https:\/\/secure.gravatar.com\/avatar\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7624a75351c836baafc75dafa4918e4293adf7e6e126ad413f152cde45628f66?s=96&d=mm&r=g","caption":"saradibruno"},"url":"https:\/\/www.pedagogia.it\/stripes\/author\/saradibruno\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/comments?post=1223"}],"version-history":[{"count":0,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts\/1223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/media\/1224"}],"wp:attachment":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/media?parent=1223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/categories?post=1223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/tags?post=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}