{"id":84,"date":"2018-04-13T14:38:57","date_gmt":"2018-04-13T12:38:57","guid":{"rendered":"http:\/\/www.pedagogia.it\/nuovostripes\/?p=84"},"modified":"2026-04-13T13:11:30","modified_gmt":"2026-04-13T11:11:30","slug":"scuole-dellinfanzia-gestione","status":"publish","type":"post","link":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/","title":{"rendered":"SCUOLE DELL\u2019INFANZIA IN GESTIONE:"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container boomapps_vcrow\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 boomapps_vccolumn single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell  boomapps_vccolumn no-block-padding\" ><div class=\"uncont\" ><div class=\"vc_custom_heading_wrap \"><div class=\"heading-text el-text\" ><h2 class=\"h2\" ><span>Scuola dell&#8217;infanzia<\/span><\/h2><\/div><div class=\"clear\"><\/div><\/div><div class=\"uncode_text_column\" ><p><span style=\"font-weight: 400;\"><strong>La scuola dell\u2019infanzia<\/strong> si rivolge a tutte le bambine e i bambini <strong>dai tre ai sei anni <\/strong><\/span><span style=\"font-weight: 400;\"><strong>di et\u00e0<\/strong> ed \u00e8 la risposta al loro <strong>diritto all\u2019educazione e alla cura<\/strong>, in coerenza con i principi di pluralismo culturale ed istituzionale presenti nella <span style=\"text-decoration: underline;\">Costituzione della Repubblica<\/span>, <span style=\"text-decoration: underline;\">nella Convenzione sui diritti dell\u2019infanzia e dell\u2019adolescenza<\/span> e <span style=\"text-decoration: underline;\">nei documenti dell\u2019Unione europea<\/span>. Essa si pone la finalit\u00e0 di promuovere nei bambini lo sviluppo dell\u2019identit\u00e0, dell\u2019autonomia, della competenza e <strong>li avvia alla cittadinanza<\/strong>, cos\u00ec come previsto nelle Indicazioni Nazionali per il Curricolo della scuola dell\u2019infanzia e primo ciclo.<br \/>\n<\/span><span style=\"font-weight: 400;\">Tale servizio si connota come luogo di promozione della cultura dell\u2019infanzia, dello sviluppo globale e armonico del bambino, nel rispetto dei tempi di crescita individuali e in una dimensione di<strong> ascolto dei bisogni dei bambini e delle loro famiglie<\/strong> attraverso l\u2019organizzazione di un ambiente di vita, di relazioni e di apprendimento di qualit\u00e0, garantito dalla professionalit\u00e0 degli operatori e dal dialogo sociale ed educativo con le famiglie e con la comunit\u00e0.<\/span><\/p>\n<\/div><div class=\"uncode_text_column\" ><\/p>\n<p class=\"p1\"><b>SCUOLE DELL\u2019INFANZIA IN GESTIONE:<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Scuola dell\u2019infanzia Giuditta Pizzamiglio di Gaggiano <\/span><\/li>\n<li>Scuola dell\u2019infanzia Carla Pianca di Bonirola-Gaggiano<\/li>\n<li>Scuola dell\u2019infanzia Don Angelo Luzzini di Cantalupo-Cerro Maggiore<\/li>\n<li>Scuola dell\u2019infanzia <a href=\"https:\/\/www.pedagogia.it\/stripes\/il-villaggio-dei-bambini-scuola-dellinfanzia-stripes-coop\/\"><span style=\"color: #333399;\">Il Villaggio dei bambini di Desio<\/span><\/a><\/li>\n<\/ul>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Scuola dell'infanziaLa scuola dell\u2019infanzia si rivolge a tutte le bambine e i bambini dai tre ai sei anni di et\u00e0 [...]","protected":false},"author":1,"featured_media":304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-84","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zerosei"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/\" \/>\n<meta property=\"og:site_name\" content=\"Stripes Cooperativa Sociale ONLUS\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-13T12:38:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T11:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raul Jannone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raul Jannone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/\"},\"author\":{\"name\":\"Raul Jannone\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/6ef94b1703cc542d2cfed879ddf74507\"},\"headline\":\"SCUOLE DELL\u2019INFANZIA IN GESTIONE:\",\"datePublished\":\"2018-04-13T12:38:57+00:00\",\"dateModified\":\"2026-04-13T11:11:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/\"},\"wordCount\":246,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/04\\\/zerosei.jpg\",\"articleSection\":[\"zerosei\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/\",\"name\":\"SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/04\\\/zerosei.jpg\",\"datePublished\":\"2018-04-13T12:38:57+00:00\",\"dateModified\":\"2026-04-13T11:11:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/6ef94b1703cc542d2cfed879ddf74507\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/04\\\/zerosei.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2018\\\/04\\\/zerosei.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/scuole-dellinfanzia-gestione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCUOLE DELL\u2019INFANZIA IN GESTIONE:\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#website\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/\",\"name\":\"Stripes Cooperativa Sociale ONLUS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/#\\\/schema\\\/person\\\/6ef94b1703cc542d2cfed879ddf74507\",\"name\":\"Raul Jannone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g99cbb35172e43f714c5f48bcbd1c7ca6\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g\",\"caption\":\"Raul Jannone\"},\"description\":\"Info bibliografiche\",\"url\":\"https:\\\/\\\/www.pedagogia.it\\\/stripes\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/","og_locale":"it_IT","og_type":"article","og_title":"SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS","og_url":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/","og_site_name":"Stripes Cooperativa Sociale ONLUS","article_published_time":"2018-04-13T12:38:57+00:00","article_modified_time":"2026-04-13T11:11:30+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg","type":"image\/jpeg"}],"author":"Raul Jannone","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Raul Jannone","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#article","isPartOf":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/"},"author":{"name":"Raul Jannone","@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/6ef94b1703cc542d2cfed879ddf74507"},"headline":"SCUOLE DELL\u2019INFANZIA IN GESTIONE:","datePublished":"2018-04-13T12:38:57+00:00","dateModified":"2026-04-13T11:11:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/"},"wordCount":246,"commentCount":0,"image":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg","articleSection":["zerosei"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/","url":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/","name":"SCUOLE DELL\u2019INFANZIA IN GESTIONE: - Stripes Cooperativa Sociale ONLUS","isPartOf":{"@id":"https:\/\/www.pedagogia.it\/stripes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#primaryimage"},"image":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg","datePublished":"2018-04-13T12:38:57+00:00","dateModified":"2026-04-13T11:11:30+00:00","author":{"@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/6ef94b1703cc542d2cfed879ddf74507"},"breadcrumb":{"@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#primaryimage","url":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg","contentUrl":"https:\/\/www.pedagogia.it\/stripes\/wp-content\/uploads\/sites\/7\/2018\/04\/zerosei.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/www.pedagogia.it\/stripes\/scuole-dellinfanzia-gestione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pedagogia.it\/stripes\/"},{"@type":"ListItem","position":2,"name":"SCUOLE DELL\u2019INFANZIA IN GESTIONE:"}]},{"@type":"WebSite","@id":"https:\/\/www.pedagogia.it\/stripes\/#website","url":"https:\/\/www.pedagogia.it\/stripes\/","name":"Stripes Cooperativa Sociale ONLUS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pedagogia.it\/stripes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.pedagogia.it\/stripes\/#\/schema\/person\/6ef94b1703cc542d2cfed879ddf74507","name":"Raul Jannone","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g99cbb35172e43f714c5f48bcbd1c7ca6","url":"https:\/\/secure.gravatar.com\/avatar\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44fd933c75f5ee9b96f27834e4b1f3d2e7e56504291af13b42785c2b1a53944a?s=96&d=mm&r=g","caption":"Raul Jannone"},"description":"Info bibliografiche","url":"https:\/\/www.pedagogia.it\/stripes\/author\/admin\/"}]}},"authors":[],"_links":{"self":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/comments?post=84"}],"version-history":[{"count":1,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts\/84\/revisions"}],"predecessor-version":[{"id":26817,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/posts\/84\/revisions\/26817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/media?parent=84"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/categories?post=84"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pedagogia.it\/stripes\/wp-json\/wp\/v2\/tags?post=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}